{"id":5,"date":"2025-03-16T16:22:26","date_gmt":"2025-03-16T16:22:26","guid":{"rendered":"http:\/\/ddce.du.ac.in\/wordpress\/dashboard\/"},"modified":"2025-03-16T16:22:26","modified_gmt":"2025-03-16T16:22:26","slug":"dashboard","status":"publish","type":"page","link":"https:\/\/ddce.du.ac.in\/wordpress\/dashboard\/","title":{"rendered":"Dashboard"},"content":{"rendered":"<div class=\"academy-login-form-wrapper\">\n\t\t\t<h2 class=\"academy-login-form-heading\">Sign in to Access Your Dashboard<\/h2>\n\t\t\t<div class=\"academy-login-form-status\"><\/div>\n\t<form id=\"academy_login_form\" class=\"academy-login-form\" action=\"#\" method=\"post\">\n\t\t<input type=\"hidden\" id=\"_wpnonce\" name=\"_wpnonce\" value=\"2be8ffb253\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/wordpress\/wp-json\/wp\/v2\/pages\/5\" \/>\t\t<input type=\"hidden\" name=\"login_redirect_url\" value=\"https:\/\/ddce.du.ac.in\/wordpress\/dashboard\/\">\n\t\t<div class=\"academy-form-group\">\n\t\t\t\t\t\t<label for=\"username\">Username or Email Address<\/label>\n\t\t\t\t\t\t\t<input id=\"username\" type=\"text\" class=\"academy-form-control\" name=\"username\" value=\"\" placeholder=\"Username or Email Address\">\n\t\t<\/div>\n\t\t<div class=\"academy-form-group\">\n\t\t\t\t\t\t<label for=\"password\">Password<\/label>\n\t\t\t\t\t\t\t<div>\n\t\t\t\t<input id=\"password\" type=\"password\" class=\"academy-form-control\" name=\"password\" value=\"\" placeholder=\"Password\">\n\t\t\t\t<span id=\"password-icon\" class=\"toggle-password academy-icon academy-icon--eye\"><\/span>\n\t\t\t<\/div>\n\n\t\t<\/div>\n\t\t<div class=\"academy-form-group academy-d-flex academy-flex-row academy-justify-content-between\">\n\t\t\t<div class=\"academy-form-group__forgetmenot\">\n\t\t\t\t<label><input type=\"checkbox\" name=\"remember\"> Remember me<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"academy-form-group__inner\">\n\t\t\t\t<a class=\"academy-form-text-link\" href=\"https:\/\/ddce.du.ac.in\/wordpress\/password-reset\/\">Reset password<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"academy-form-group\">\n\t\t\t<button class=\"academy-btn academy-btn--bg-purple\" type=\"submit\">Log In<\/button>\n\t\t<\/div>\n\t<\/form>\n\t<p class=\"academy-login-form-info\">Don&#039;t have an account?  <a href=\"https:\/\/ddce.du.ac.in\/wordpress\/student-registration\/?redirect_to=https:\/\/ddce.du.ac.in\/wordpress\/dashboard\/\">Register Now<\/a><\/p>\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sign in to Access Your Dashboard Username or Email Address Password Remember me Reset password Log In Don&#039;t have an account? Register Now<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"academy-canvas.php","meta":{"footnotes":""},"class_list":["post-5","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ddce.du.ac.in\/wordpress\/wp-json\/wp\/v2\/pages\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ddce.du.ac.in\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ddce.du.ac.in\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ddce.du.ac.in\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ddce.du.ac.in\/wordpress\/wp-json\/wp\/v2\/comments?post=5"}],"version-history":[{"count":0,"href":"https:\/\/ddce.du.ac.in\/wordpress\/wp-json\/wp\/v2\/pages\/5\/revisions"}],"wp:attachment":[{"href":"https:\/\/ddce.du.ac.in\/wordpress\/wp-json\/wp\/v2\/media?parent=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}